{"id":3113,"date":"2013-01-29T16:05:38","date_gmt":"2013-01-29T16:05:38","guid":{"rendered":"http:\/\/www.tvmasmagazine.com\/?p=3113"},"modified":"2015-01-27T12:01:29","modified_gmt":"2015-01-27T11:01:29","slug":"telefe-crea-alianza-con-youtube","status":"publish","type":"post","link":"https:\/\/tvmasmagazine.com\/es\/2013\/01\/29\/telefe-crea-alianza-con-youtube\/","title":{"rendered":"TELEFE CREA ALIANZA CON YOUTUBE"},"content":{"rendered":"<p><\/p>\n<h3> A trav\u00e9s de la plataforma, los usuarios tendr\u00e1n acceso a m\u00e1s de 930 horas de contenidos originales de la cadena argentina<\/h3>\n<p><div id=\"attachment_3114\" style=\"width: 410px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/Mike-Mecham-400.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3114\" src=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/Mike-Mecham-400.jpg\" alt=\"\" title=\"Mike-Mecham-400\" width=\"400\" height=\"240\" class=\"size-full wp-image-3114\" srcset=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/Mike-Mecham-400.jpg 400w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/Mike-Mecham-400-150x90.jpg 150w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/Mike-Mecham-400-350x210.jpg 350w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-3114\" class=\"wp-caption-text\">Mike Mecham, gerente de alianzas de contenido de YouTube para el Cono Sur<\/p><\/div>Telefe dio a conocer el acuerdo con YouTube como Partner, en el marco de potenciar los contenidos para multiplataformas. Ya est\u00e1n disponibles en YouTube los  canales youtube.com\/user\/oficialtelefe   y  youtube.com\/user\/telefenoticias con m\u00e1s de 930 horas de contenido original, equivalente a un mes entero de programaci\u00f3n 24 horas.<\/p>\n<p><a href=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/logo-telefe.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/logo-telefe-300x58.jpg\" alt=\"\" title=\"logo telefe\" width=\"300\" height=\"58\" class=\"alignleft size-medium wp-image-3115\" \/><\/a>\u201cCelebramos que Telefe haya elegido a YouTube como plataforma para distribuir su contenido original. Esta alianza no s\u00f3lo permite acercar a la audiencia online contenido en espa\u00f1ol de alt\u00edsima calidad, sino que demuestra c\u00f3mo la nueva generaci\u00f3n de canales incorpora al video online como un componente estrat\u00e9gico y complementario\u00bb, coment\u00f3 Mike Mecham, gerente de alianzas de contenido de YouTube para el Cono Sur.<\/p>\n<p><a href=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/LOGO-YOUTUBE.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/LOGO-YOUTUBE.jpg\" alt=\"\" title=\"LOGO YOUTUBE\" width=\"204\" height=\"204\" class=\"alignright size-full wp-image-3116\" srcset=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/LOGO-YOUTUBE.jpg 204w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2013\/01\/LOGO-YOUTUBE-150x150.jpg 150w\" sizes=\"auto, (max-width: 204px) 100vw, 204px\" \/><\/a>Entre el cat\u00e1logo que ofrece, se encuentran exitosas producciones como:  Chiquititas, Pon\u00e9 a Francella, El hombre de tu vida, El elegido, Los Rold\u00e1n, Vidas Robadas, Los Exitosos Pells, La Due\u00f1a entre muchos otros. Adem\u00e1s en youtube\/oficialtelefe se estren\u00f3, de manera exclusiva, el Teaser en 3D de la nueva pel\u00edcula de Juan Jose Campanella \u201cMetegol\u201d.<\/p>\n<p>Por otra parte, se complementan la propuestas en video online con iniciativas para relacionarse con el p\u00fablico: a trav\u00e9s de su p\u00e1gina de Google+ , se realizan hangouts en vivo (videconferencias que se transmiten en simult\u00e1neo por YouTube) con artistas y programas en exclusiva.<\/p>\n<p>Por su parte Telefe.com aloja todo el contenido de la pantalla, material exclusivo, entrevistas, grilla de programaci\u00f3n, episodios completos, Telefe Noticias, y mucho m\u00e1s.<\/p>","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la plataforma, los usuarios tendr\u00e1n acceso a m\u00e1s de 930 horas de contenidos originales de la cadena <a class=\"more-link\" href=\"https:\/\/tvmasmagazine.com\/es\/2013\/01\/29\/telefe-crea-alianza-con-youtube\/\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[],"class_list":["post-3113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-telenovelas-series"],"_links":{"self":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/3113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/comments?post=3113"}],"version-history":[{"count":2,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/3113\/revisions"}],"predecessor-version":[{"id":8185,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/3113\/revisions\/8185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/media\/3117"}],"wp:attachment":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/media?parent=3113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/categories?post=3113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/tags?post=3113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}