{"id":66605,"date":"2023-05-05T00:11:58","date_gmt":"2023-05-05T03:11:58","guid":{"rendered":"https:\/\/tvmasmagazine.com\/?p=66605"},"modified":"2023-05-05T00:11:58","modified_gmt":"2023-05-05T03:11:58","slug":"hola-tv-pondra-toda-la-carne-en-el-asador-con-transmision-en-vivo-de-la-coronacion-de-carlos-iii","status":"publish","type":"post","link":"https:\/\/tvmasmagazine.com\/es\/2023\/05\/05\/hola-tv-pondra-toda-la-carne-en-el-asador-con-transmision-en-vivo-de-la-coronacion-de-carlos-iii\/","title":{"rendered":"\u00a1HOLA! TV \u2018Pondr\u00e1 toda la carne en el asador\u2019 con transmisi\u00f3n en vivo de la coronaci\u00f3n de Carlos III"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-66606 size-full\" src=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar.jpeg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar.jpeg 1600w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar-350x197.jpeg 350w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar-1024x576.jpeg 1024w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar-150x84.jpeg 150w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar-768x432.jpeg 768w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/05\/descargar-1536x864.jpeg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p><span style=\"color: #000080;\"><strong>Oriana P\u00e9rez, Julio Otero y Luc\u00eda Ria\u00f1o, y desde Londres Marcela Guti\u00e9rrez, analizar\u00e1n todos los detalles en los diferentes programas especiales dedicados a este hist\u00f3rico momento.<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>El canal de pago se ha ganado el coraz\u00f3n de las audiencias de Latinoam\u00e9rica y Estados Unidos como el canal de referencia en informaci\u00f3n sobre realeza. Este s\u00e1bado 6 de mayo sale a conquistar a su p\u00fablico con la coronaci\u00f3n de Carlos III, el evento del a\u00f1o en el Reino Unido.<\/strong><\/span><\/p>\n<p>\u00a1HOLA! TV, pone todos sus recursos para llevar a la audiencia los detalles de esta gran celebraci\u00f3n, empezando con la transmisi\u00f3n en vivo (a partir de las 2:30 am de M\u00e9xico). Y, todo lo que suceda, ir\u00e1 acompa\u00f1ado de los comentarios y an\u00e1lisis de los expertos en realeza, Oriana P\u00e9rez y Julio Otero, y de la corresponsal en Londres, Marcela Guti\u00e9rrez.<\/p>\n<p>El mismo s\u00e1bado, en prime time, \u00a1HOLA! TV ha preparado <strong>Especiales \u00a1HOLA! TV<\/strong>: \u2018Una ceremonia para un nuevo rey\u2019, en el que Luc\u00eda Ria\u00f1o y Oriana P\u00e9rez seleccionar\u00e1n los momentos m\u00e1s significativos de la jornada, con el apoyo de Marcela Guti\u00e9rrez para acercar el ambiente festivo que invade la capital brit\u00e1nica. Le seguir\u00e1 un resumen de hora y media con un recorrido visual.<\/p>\n<p>\u201cComo en los grandes momentos que protagonizan las familias reales del mundo, y que marcan la historia, \u00a1HOLA! TV volver\u00e1 a ser un referente a la hora de acercar, con rigor y con nuestro particular estilo, lo que suceder\u00e1 durante la coronaci\u00f3n del Rey, pero tambi\u00e9n estaremos presentes antes y despu\u00e9s del gran d\u00eda con nuestra programaci\u00f3n, para darle el prestigio merecido a este importante evento como ning\u00fan otro canal puede hacerlo\u201d, asegura <strong>Adolfo \u00c1lvarez, director de contenidos <\/strong>de \u00a1HOLA! TV.<\/p>\n<p>El canal adem\u00e1s de la programaci\u00f3n extraordinaria va m\u00e1s all\u00e1 del 6 de mayo y durante toda la semana previa LA HORA \u00a1HOLA! Presentar\u00e1 novedades, avances, preparativos y reacciones que se han ido produciendo.<\/p>\n<p><span style=\"color: #ff0000;\">Para disfrutar la celebraci\u00f3n continuar\u00e1 dos d\u00edas m\u00e1s<\/span>, el lunes 8 de mayo, el programa diario que presenta <strong>Natasha Cheij<\/strong> har\u00e1 eco de los mejores momentos y an\u00e9cdotas en \u2018LA HORA \u00a1HOLA!: \u2018Especial Coronaci\u00f3n\u2019, as\u00ed como del gran concierto de iconos internacionales y estrellas del momento, que se celebrar\u00e1 en el castillo de Windsor, y al que seguir\u00e1n diferentes eventos de car\u00e1cter social y cultural por las calles de la capital.<\/p>\n<p>S\u00c1BADO, 6 DE MAYO<\/p>\n<p><span style=\"background-color: yellow;\">EN VIVO &#8211; TRANSMISI\u00d3N DE LA CORONACI\u00d3N DE CARLOS III<\/span><\/p>\n<p>LATAM: 2:30AM MX\/ 3:30AM COL\/ 4:30AM VEN\/ 5:30AM ARG<\/p>\n<p>US: 4:30AM ET\/ 1:30AM PT<\/p>\n<p><span style=\"background-color: yellow;\">ESPECIALES \u00a1HOLA! TV:<\/span> \u2018UNA CEREMONIA PARA UN NUEVO REY\u2019<\/p>\n<p>LATAM: 8:00PM MX\/ 9:00PM COL\/ 10:00PM VEN\/ 11:00PM ARG<\/p>\n<p>US: 10:00PM \/ 9:00PM C<\/p>\n<p><span style=\"background-color: yellow;\">RESUMEN CORONACI\u00d3N CARLOS III<\/span><\/p>\n<p>LATAM: 9:00PM MX\/ 10:00PM COL\/ 11:00PM VEN\/ 00:00PM ARG<\/p>\n<p>US: 11:00PM ET\/ 8:00PM PT<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-66269 alignleft\" src=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/02\/Redaccion-TVMAS-150x30.png\" alt=\"\" width=\"150\" height=\"30\" srcset=\"https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/02\/Redaccion-TVMAS-150x30.png 150w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/02\/Redaccion-TVMAS-350x70.png 350w, https:\/\/tvmasmagazine.com\/wp-content\/uploads\/2023\/02\/Redaccion-TVMAS.png 745w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Oriana P\u00e9rez, Julio Otero y Luc\u00eda Ria\u00f1o, y desde Londres Marcela Guti\u00e9rrez, analizar\u00e1n todos los detalles en los diferentes programas <a class=\"more-link\" href=\"https:\/\/tvmasmagazine.com\/es\/2023\/05\/05\/hola-tv-pondra-toda-la-carne-en-el-asador-con-transmision-en-vivo-de-la-coronacion-de-carlos-iii\/\">&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":66606,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/66605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/comments?post=66605"}],"version-history":[{"count":2,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/66605\/revisions"}],"predecessor-version":[{"id":66608,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/posts\/66605\/revisions\/66608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/media\/66606"}],"wp:attachment":[{"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/media?parent=66605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/categories?post=66605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvmasmagazine.com\/es\/wp-json\/wp\/v2\/tags?post=66605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}